{"id":6509,"date":"2024-10-21T08:43:51","date_gmt":"2024-10-21T06:43:51","guid":{"rendered":"https:\/\/pro.beautyproject.ch\/prodotto\/kinetics-shield-gel-polish-schoenheit-in-dna-454\/"},"modified":"2025-08-20T14:49:07","modified_gmt":"2025-08-20T12:49:07","slug":"kinetics-shield-gel-polish-schoenheit-in-dna-454","status":"publish","type":"product","link":"https:\/\/pro.beautyproject.ch\/de\/produkt\/kinetics-shield-gel-polish-schoenheit-in-dna-454\/","title":{"rendered":"Kinetics SHIELD Gel Polish Beauty in DNA #454"},"content":{"rendered":"<p>F\u00e4rbung: Nude hellrosa<\/p>\n<p>Teil der Kollektion:<strong> <\/strong><\/p>\n<p><strong>USE<\/strong><\/p>\n<p>1. Desinfizieren Sie Ihre H\u00e4nde mit Pro Hand Sanitiser Spray und f\u00fchren Sie eine Manik\u00fcre durch (dry mit Hilfe des Bohrers oder klassisch) und formen Sie die N\u00e4gel mit der Feile Miss Rhino (wei\u00dfe Seite). Eventuelles Abstumpfen der Folie k\u00f6nnen Sie mit der grauen Seite der Feile erledigen.<br \/>\n2. Reinigen Sie alle N\u00e4gel mit einem in Di-Tack Cleanser getr\u00e4nkten Wattest\u00e4bchen, um \u00d6l und Staub zu entfernen, und tragen Sie den Dehidrator auf und lassen Sie ihn einige Sekunden lang verdunsten.<br \/>\n3. Tragen Sie eine SHIELD\u2122 Base Ihrer Wahl auf und h\u00e4rten Sie sie unter der LED-Lampe f\u00fcr 30 Sekunden aus.<br \/>\n4. Tragen Sie eine leichte Schicht SHIELD\u2122 Farbe Ihrer Wahl auf und achten Sie dabei darauf, auch die freie Kante zu versiegeln, und h\u00e4rten Sie sie 30 Sekunden lang unter einer LED-Lampe aus.<br \/>\n5. F\u00fcr ultra-pigmentierte Deckkraft, wiederholen Sie Schritt 4.<br \/>\n6. Tragen Sie ein SHIELD\u2122 Top Coat Ihrer Wahl auf. Achten Sie darauf, dass die Farbe vollst\u00e4ndig bedeckt ist, indem Sie sie 30 Sekunden lang in einer LED-Lampe aush\u00e4rten.<br \/>\n7. Entfernen Sie jegliche Inhibitionsschicht mit Di-Tack Cleanser.<br \/>\n8. Beenden Sie den Service, indem Sie Kinetics Cuticle Oil auf den Nagelhautring auftragen.<\/p>\n<p><strong>Entfernung<\/strong>: Entfernen Sie das Produkt mechanisch mit dem Cutter oder der Entfernungsfl\u00fcssigkeit. Kinetics Gel Polish Remover Red Lizard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Professioneller, hochpigmentierter dreiphasiger semipermanenter Nagellack. Intensive Farben und Aush\u00e4rtung unter UV\/LED-Lampen sorgen f\u00fcr perfekte Deckkraft und Haltbarkeit f\u00fcr bis zu 28 Tage. <\/p>\n<p>HEMA und 16-fache GRATIS-Formel f\u00fcr wirklich verl\u00e4ssliche Sicherheit, um reizende Hautreaktionen bei Kunden und Mitarbeitern zu reduzieren.<\/p>\n<p>Beauty in DNA #454<\/p>\n","protected":false},"featured_media":4110,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"product_brand":[],"product_cat":[108],"product_tag":[],"class_list":{"0":"post-6509","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-shield-colors-de","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/product\/6509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/media\/4110"}],"wp:attachment":[{"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/media?parent=6509"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/product_brand?post=6509"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/product_cat?post=6509"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/de\/wp-json\/wp\/v2\/product_tag?post=6509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}