{"id":5487,"date":"2024-10-21T08:43:11","date_gmt":"2024-10-21T06:43:11","guid":{"rendered":"https:\/\/pro.beautyproject.ch\/prodotto\/kinetics-solargel-polish-electra-461\/"},"modified":"2025-03-03T11:42:46","modified_gmt":"2025-03-03T10:42:46","slug":"kinetics-solargel-polish-electra-461","status":"publish","type":"product","link":"https:\/\/pro.beautyproject.ch\/fr\/produit\/kinetics-solargel-polish-electra-461\/","title":{"rendered":"Kinetics SolarGel Polish Electra #461"},"content":{"rendered":"<p>Coloration : jaune fluo<\/p>\n<p>Fait partie de la collection :<\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>UTILISER<\/strong><\/p>\n<p>1. D\u00e9sinfectez vos mains avec Pro Hand Sanitiser Spray et r\u00e9alisez une manucure (dry \u00e0 l&#8217;aide de la fraise ou du classique) et fa\u00e7onnez les ongles \u00e0 l&#8217;aide de la lime Miss Rhino (c\u00f4t\u00e9 blanc). L&#8217;\u00e9ventuel ternissement de la feuille peut \u00eatre fait avec le c\u00f4t\u00e9 gris de la lime.<br \/>\n2. Nettoyez les 10 ongles \u00e0 l&#8217;aide d&#8217;un coton-tige imbib\u00e9 d&#8217;eau. Lizard Polish Remover pour \u00e9liminer les r\u00e9sidus d&#8217;huile et de poussi\u00e8re et appliquez une couche de base de votre choix sp\u00e9cifique \u00e0 chaque type d&#8217;ongle.<br \/>\n3. Appliquez une l\u00e9g\u00e8re couche de SolarGel de votre choix, en prenant soin de sceller \u00e9galement le bord libre.  Attendez environ 2 minutes pour que la couleur s\u00e8che parfaitement.<br \/>\n4. Pour une couverture ultra-pigment\u00e9e, r\u00e9p\u00e9tez l&#8217;\u00e9tape 3.<br \/>\n5. Appliquez Kwik-Kote (s\u00e9chage rapide) ou alternativement le Solar Gel Top Coat (r\u00e9serv\u00e9 aux professionnels) en prenant soin de couvrir compl\u00e8tement la couleur et attendez le s\u00e9chage complet du produit.<br \/>\nNB. Pour acc\u00e9l\u00e9rer le temps de s\u00e9chage du Solar Gel Top Coat (r\u00e9serv\u00e9 aux professionnels), utilisez Kwik Dry Drops pour s\u00e9cher l&#8217;\u00e9mail.<br \/>\n6. Terminez le service en appliquant dans le cercle \u00e0 cuticules Orange, Almond o Lemon Cuticle Oil en prenant soin de ne pas toucher la plaque de l&#8217;ongle. <\/p>\n<p><strong>Retrait<\/strong>: retirez le produit m\u00e9caniquement \u00e0 l&#8217;aide d&#8217;un cutter ou d&#8217;un liquide de retrait. Kinetics Gel Polish Remover Red Lizard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une formule d&#8217;\u00e9mail \u00e0 deux phases qui, envelopp\u00e9e dans un scellant r\u00e9sistant aux rayures, garantit une r\u00e9sistance in\u00e9gal\u00e9e par rapport aux \u00e9maux traditionnels : jusqu&#8217;\u00e0 10 jours avec un effet incroyable et ultra-brillant gel.<\/p>\n<p>Electra #461<\/p>\n","protected":false},"featured_media":3164,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"product_brand":[],"product_cat":[119],"product_tag":[],"class_list":{"0":"post-5487","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-solargel-fr","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/product\/5487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/media\/3164"}],"wp:attachment":[{"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/media?parent=5487"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=5487"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=5487"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pro.beautyproject.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=5487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}